{"id":801,"date":"2008-11-11T00:00:00","date_gmt":"2008-11-11T00:00:00","guid":{"rendered":"https:\/\/comunicatur.info\/els-majoristes-britanics-mantenen-les-reserves-a-la-costa-daurada-pel-2009-2\/"},"modified":"2008-11-11T00:00:00","modified_gmt":"2008-11-11T00:00:00","slug":"els-majoristes-britanics-mantenen-les-reserves-a-la-costa-daurada-pel-2009-2","status":"publish","type":"post","link":"https:\/\/www.comunicatur.info\/es\/els-majoristes-britanics-mantenen-les-reserves-a-la-costa-daurada-pel-2009-2\/","title":{"rendered":"Los mayoristas brit\u00e1nicos mantienen las reservas en la Costa Daurada para 2009"},"content":{"rendered":"<p>La Asociaci&oacute;n Hotelera Salou-Cambrils-La Pineda hacen un balance positivo de la temporada tur&iacute;stica a pesar de haber perdido un 5% de ocupaci&oacute;n. Para 2009 las perspectivas son buenas ya que los principales operadores brit&aacute;nicos habr&iacute;an confirmado que mantendr&aacute;n el mismo nivel de reservas que esta temporada.<\/p>\n<p><\/p>\n<p>Los turistas brit&aacute;nicos son el principal mercado extranjero y representan casi la mitad del turismo internacional para Salou, Cambrils y La Pineda. Seg&uacute;n los hoteleros, los mayoristas de este mercado han reservado para el pr&oacute;ximo a&ntilde;o los mismos n&uacute;meros que para el 2008.<\/p>\n<p>El balance sobre la temporada actual, realizado por los hoteleros tarraconenses, es positivo porque consideran que han resistido bien y no han tenido un descenso pronunciado como otros destinos. El vicepresidente de la asociaci&oacute;n, Joan Antoni Padr&oacute;, ha afirmado que son una de los destinos de sol y playa espa&ntilde;oles que mejor ha aguantado la crisis. A pesar de todo, la ocupaci&oacute;n de enero a septiembre ha bajado del 81% al 76% en un a&ntilde;o.<\/p>\n<p>Otro dato destacado ha sido el descenso del consumo de los visitantes en la Costa Daurada. El poder adquisitivo o la capacidad de gasto se ha reducido considerablemente, en algunos casos hasta un 20%. Ponen como ejemplo la apreciaci&oacute;n del euro frente a la libra esterlina brit&aacute;nica y el rublo ruso que habr&iacute;a supuesto un encarecimiento de las vacaciones de un 25% sin que los empresarios hayan subido el precio.<\/p>\n<p>Por otro lado, la asociaci&oacute;n hotelera ha querido apostar por la denominaci&oacute;n Costa Daurada y ha pedido que las principales infraestructuras, aeropuerto de Reus o estaci&oacute;n del AVE, incluyan en su nombre la identificaci&oacute;n Costa Daurada. Se a&ntilde;aden as&iacute; a las peticiones que diferentes colectivos empresariales del territorio est&aacute;n realizando &uacute;ltimamente sobre la denominaci&oacute;n de estas infraestructuras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci&oacute;n Hotelera Salou-Cambrils-La Pineda hacen un balance positivo de la temporada tur&iacute;stica a pesar de haber perdido un 5% de ocupaci&oacute;n. Para 2009 las perspectivas son buenas ya que los principales operadores brit&aacute;nicos habr&iacute;an confirmado que mantendr&aacute;n el mismo nivel de reservas que esta temporada.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"close","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/801"}],"collection":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/comments?post=801"}],"version-history":[{"count":0,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/801\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/media?parent=801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/categories?post=801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/tags?post=801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}