{"id":6299,"date":"2014-10-07T00:00:34","date_gmt":"2014-10-06T22:00:34","guid":{"rendered":"https:\/\/comunicatur.info\/?p=6299"},"modified":"2014-10-05T18:48:28","modified_gmt":"2014-10-05T16:48:28","slug":"lloret-de-mar-sera-uno-de-los-destinos-que-se-comercialicen-dentro-del-programa-europe-senior-tourism-2014-de-segittur","status":"publish","type":"post","link":"https:\/\/www.comunicatur.info\/es\/lloret-de-mar-sera-uno-de-los-destinos-que-se-comercialicen-dentro-del-programa-europe-senior-tourism-2014-de-segittur\/","title":{"rendered":"Lloret de Mar ser\u00e1 uno de los destinos que se comercialicen dentro del programa Europe Senior Tourism 2014 de SEGITTUR"},"content":{"rendered":"<p>Lloret de Mar ser\u00e1 nuevamente uno de los destinos seleccionados para formar parte del proyecto de la Secretar\u00eda de Estado de Turismo (SEGITTUR), para la comercializaci\u00f3n de paquetes de viajes en el marco del programa Europe Senior Tourism 2014.<\/p>\n<p>El programa consiste en paquetes tur\u00edsticos dirigidos a turistas senior, con propuestas de alojamiento y actividades, que se comercializar\u00e1n en 17 pa\u00edses de la Uni\u00f3n Europea: Polonia, la Rep\u00fablica Checa, Eslovaquia, Ruman\u00eda, Bulgaria, Finlandia, Francia, Reino Unido, Suecia, Italia, Grecia, Austria, Irlanda, Portugal, Lituania, Hungr\u00eda y Alemania.<\/p>\n<p>Estos paquetes tur\u00edsticos se vender\u00e1n a trav\u00e9s de cinco agencias seleccionadas que son Turismo Vivencial, EUROSENIOR, Serhs Turismo, Sureste Incoming y Delf\u00edn Travel. En palabras de Jordi Orobitg, concejal de Turismo: \u00abDesde Lloret Turismo celebramos que Lloret de Mar haya sido seleccionada para formar parte de este programa que favorecer\u00e1 una mayor desestacionalizaci\u00f3n del destino, a la vez que permitir\u00e1 dar a conocer la oferta complementaria y los atractivos culturales m\u00e1s destacados de Lloret en este segmento de p\u00fablico senior. En este sentido se est\u00e1 trabajando para que estas agencias incluyan la tarjeta <a href=\"http:\/\/lloretdemar.org\/es\/que-hacer\/lloretcard\" target=\"_blank\" rel=\"noopener\">Lloret Senior Card<\/a> en sus paquetes de viajes\u00bb.<\/p>\n<p>Seg\u00fan datos de Eurostat, en 2030 el grupo de personas de 65 a\u00f1os o m\u00e1s de los 27 miembros de la Uni\u00f3n Europea pasar\u00e1 de integrar el 17,4% de la poblaci\u00f3n total al 26,6%. Los principales mercados emisores de turismo de Europa son Reino Unido, Francia y Alemania. En esta l\u00ednea y como producto complementario, tambi\u00e9n se mantiene como estrat\u00e9gica la apuesta de <a href=\"http:\/\/saladepremsa.lloretdemar.org\/es\/%C2%BFquienes-somos\/\" target=\"_blank\" rel=\"noopener\">Lloret Turismo<\/a> por el turismo accesible.<\/p>\n<p>Aparte de <a href=\"http:\/\/lloretdemar.org\/es\/\" target=\"_blank\" rel=\"noopener\">Lloret de Mar<\/a>, tambi\u00e9n han sido seleccionadas la Costa del Sol Occidental, Moj\u00e1car, Roquetas de Mar, El Ejido, Costa Blanca, Calella, Santa Susanna, Cazorla, \u00c9cija, Noja, Cantabria, Salamanca, El Vendrell, Plasencia, la Coru\u00f1a, Bayona, Vigo, Sanxenxo, San Antonio, Santa Eulalia del R\u00edo, Calvi\u00e0, Palma, Costa C\u00e1lida, Menorca y Navarra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lloret de Mar ser\u00e1 nuevamente uno de los destinos seleccionados para formar parte del proyecto de la Secretar\u00eda de Estado de Turismo (SEGITTUR), para la comercializaci\u00f3n de paquetes de viajes en el marco del programa Europe Senior Tourism 2014. El programa consiste en paquetes tur\u00edsticos dirigidos a turistas senior, con propuestas de alojamiento y actividades, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[62],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/6299"}],"collection":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/comments?post=6299"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/6299\/revisions"}],"predecessor-version":[{"id":6300,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/6299\/revisions\/6300"}],"wp:attachment":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/media?parent=6299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/categories?post=6299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/tags?post=6299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}