{"id":4891,"date":"2013-12-03T19:45:12","date_gmt":"2013-12-03T19:45:12","guid":{"rendered":"https:\/\/comunicatur.info\/la-gran-accio-per-lenoturisme-a-catalunya-2\/"},"modified":"2013-12-03T19:45:12","modified_gmt":"2013-12-03T19:45:12","slug":"la-gran-accio-per-lenoturisme-a-catalunya-2","status":"publish","type":"post","link":"https:\/\/www.comunicatur.info\/es\/la-gran-accio-per-lenoturisme-a-catalunya-2\/","title":{"rendered":"La gran acci\u00f3n por el enoturismo en Catalu\u00f1a"},"content":{"rendered":"<p><em><img width=\"172\" height=\"156\" src=\"https:\/\/www.comunicatur.info\/cms\/images\/stories\/fotos\/Tolosa2%20-%20copia.jpg\" alt=\"\" \/><\/em><\/p>\n<p><em>El autor propone ante la oferta creciente y diversificada de enoturismo crear un Centro en Barcelona para promocionar Catalu&ntilde;a como destino enotur&iacute;stico -Catalan Wine House-, a la vez que sirva para coordinar una serie de iniciativas p&uacute;blicas y privadas.<\/em><\/p>\n<p><\/p>\n<p>Ya ha arraigado la idea que el enoturismo es una gran oportunidad para Catalunya. &Uacute;ltimamente todo el mundo habla del tema. Se organizan jornadas, congresos, &ldquo;mesas&rdquo; de enoturismo y otros formatos de debate y planificaci&oacute;n. Y se multiplican las acciones y los planes estrat&eacute;gicos desde consejos reguladores, patronatos de turismo, consejos comarcales, diputaciones, municipios del vino, consorcios de enoturismo y tambi&eacute;n desde la Generalitat de Catalunya, a trav&eacute;s del INCAVI, Turismo de Catalu&ntilde;a y la Agencia Catalana de Turismo.<\/p>\n<p>Este dinamismo es fant&aacute;stico, pero tambi&eacute;n tiene un punto de caos que implica fragmentaci&oacute;n, descoordinaci&oacute;n de iniciativas p&uacute;blicas y privadas, discrepancias de criterio sobre el modelo de enoturismo, duplicaciones y solapamientos de competencias que se van intensificando a medida que avanza el proceso de planificaci&oacute;n de Catalunya como gran destino enotur&iacute;stico.<\/p>\n<p>En t&eacute;rminos de marketing de W. Chan Kim y Ren&eacute;e Mauborgne, vamos hacia un oc&eacute;ano rojo, te&ntilde;ido de sangre, donde se querr&aacute;n integrar acciones, criterios y estrategias conjuntas que topar&aacute;n con los modelos y las iniciativas que cada bodega y cada denominaci&oacute;n de origen han ido desarrollando los &uacute;ltimos a&ntilde;os, muchas de ellas ya integradas dentro del modelo normativo de Rutas del Vino de Espa&ntilde;a.<\/p>\n<p>&iquest;Cu&aacute;l es pues nuestro oc&eacute;ano azul del enoturismo? &iquest;Cu&aacute;l es nuestro gran mercado a conquistar? &iquest;D&oacute;nde podemos actuar sin luchas de competencias? &iquest;D&oacute;nde podemos sumar, ser m&aacute;s efectivos y obtener los mejores resultados?<\/p>\n<p>Pues, evidentemente en la ciudad de Barcelona. Es una de las ciudades m&aacute;s tur&iacute;sticas de Europa y tiene m&aacute;s de 500 bodegas a su alrededor. Es el San Francisco de Napa Valley o la Florencia de la Toscana. Y adem&aacute;s, es el gran vac&iacute;o de mercado del vino catal&aacute;n. Los barceloneses tienen que consumir vino catal&aacute;n y los visitantes que lleguen a Barcelona tienen que saber que est&aacute;n en un pa&iacute;s de vinos, con una gran oferta enotur&iacute;stica.<\/p>\n<p>Si actuamos en Barcelona, abriremos las puertas de la gran ciudad a las 12 denominaciones de origen catalanas, en lugar de ir por el territorio a alterar sus iniciativas locales. Mejoraremos la oferta tur&iacute;stica de Barcelona posicion&aacute;ndola como un destino enotur&iacute;stico, buscando visitantes de buen nivel cultural y alto poder adquisitivo, y haremos de Barcelona un centro emisor de visitantes hacia las bodegas de su alrededor.<\/p>\n<p>La mejor acci&oacute;n ser&iacute;a abrir una Wine Catalan House, o como se la quiera llamar. Y el mejor lugar es el Palau Robert, en la calle Diagonal esquina Paseo de Gr&agrave;cia. Ser&iacute;a el gran espacio para promocionar los vinos catalanes y mostrar y vender la Catalunya enotur&iacute;stica. Con un buen centro de interpretaci&oacute;n de la historia y la cultura del vino en Catalunya, con la ambici&oacute;n de ser un referente tur&iacute;stico como lo son el Museo Picasso o el Museo del Bar&ccedil;a. Con degustaciones y sesiones diarias de promoci&oacute;n de los vinos catalanes, 365 d&iacute;as al a&ntilde;o. Con Wine Bar para aprovechar el prestigio de la cocina catalana e intentar asociarla a los vinos catalanes. Con tienda de vinos catalanes, para que la gente se vaya con nuestros vinos del mismo modo que se van de Mallorca con una ensaimada. Y sobre todo, con rutas enotur&iacute;sticas organizadas diariamente: de un d&iacute;a, de fin de semana o de una semana, con veh&iacute;culo particular, minib&uacute;s con gu&iacute;a o en autocares.<\/p>\n<p>Este proyecto tiene tres grandes ventajas: hace de nuestro punto d&eacute;bil nuestro gran punto fuerte. Es muy f&aacute;cil y muy r&aacute;pido de hacer. Y se puede concebir como un negocio, no como un gasto.<\/p>\n<p>En los &uacute;ltimos tres a&ntilde;os no he encontrado a nadie en Catalunya que crea en esta idea. Tampoco he insistido mucho. Pero creo que podr&iacute;amos situar el vino catal&aacute;n como un producto de identidad de Catalunya. Podr&iacute;amos promover un nuevo sector tur&iacute;stico de alto nivel adquisitivo, que nos ayudar&iacute;a a diversificar y desestacionalizar nuestro sector tur&iacute;stico. Y tambi&eacute;n estar&iacute;amos potenciando un nuevo fil&oacute;n de ocupaci&oacute;n para tantos j&oacute;venes catalanes parados. Realmente, no s&eacute; a qu&eacute; estamos esperando.<\/p>\n<p><em><strong>Llu&iacute;s Tolosa <br \/>\n<\/strong><\/em><font size=\"1\">Soci&oacute;logo y escritor, <br \/>\nautor de una docena de libros de vinos y enoturismo, <br \/>\nentre ellos Catalunya no es California <br \/>\n<\/font><\/p>\n<p><font size=\"1\"><a name=\"fb_share\" type=\"button_count\"><\/a><\/font><\/p>\n<p><font size=\"1\"> <script src=\"http:\/\/static.ak.fbcdn.net\/connect.php\/js\/FB.Share\" type=\"text\/javascript\"><\/script><\/p>\n<p><a href=\"http:\/\/twitter.com\/share\" data-count=\"horizontal\" data-text=\"Catalan Wine House, la gran acci&oacute;n por el enoturismo en Catalu&ntilde;a v&iacute;a @comunicatur\" data-lang=\"es\" class=\"twitter-share-button\" target=\"_blank\" rel=\"noopener\">Tweet<\/a><\/p>\n<p><script type=\"text\/javascript\" src=\"http:\/\/platform.twitter.com\/widgets.js\"><\/script><\/p>\n<p><a href=\"https:\/\/www.comunicatur.info\">[HOME]<\/a><\/p>\n<p><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p><em><img width=\"172\" height=\"156\" src=\"https:\/\/www.comunicatur.info\/cms\/images\/stories\/fotos\/Tolosa2%20-%20copia.jpg\" alt=\"\" \/><\/em><\/p>\n<p><em>El autor propone ante la oferta creciente y diversificada de enoturismo crear un Centro en Barcelona para promocionar Catalu&ntilde;a como destino enotur&iacute;stico -Catalan Wine House-, a la vez que sirva para coordinar una serie de iniciativas p&uacute;blicas y privadas.<\/em><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"close","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/4891"}],"collection":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/comments?post=4891"}],"version-history":[{"count":0,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/4891\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/media?parent=4891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/categories?post=4891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/tags?post=4891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}