{"id":320,"date":"2008-05-26T00:00:00","date_gmt":"2008-05-26T00:00:00","guid":{"rendered":"https:\/\/comunicatur.info\/amancio-lopez-president-del-grup-hotusa-4\/"},"modified":"2008-05-26T00:00:00","modified_gmt":"2008-05-26T00:00:00","slug":"amancio-lopez-president-del-grup-hotusa-4","status":"publish","type":"post","link":"https:\/\/www.comunicatur.info\/es\/amancio-lopez-president-del-grup-hotusa-4\/","title":{"rendered":"Amancio L\u00f3pez, presidente del Grupo Hotusa"},"content":{"rendered":"<p>&quot;Estamos en el libre mercado y no creo que sea bueno pedir restricciones o moratorias de ning&uacute;n tipo; que sea el propio mercado quien diga si son necesarios tantos hoteles&quot;<\/p>\n<p><em><img class=\"\" height=\"179\" alt=\"\" width=\"153\" src=\"https:\/\/www.comunicatur.info\/cms\/images\/stories\/fotos\/AmancioLopez.jpg\" \/><\/em><\/p>\n<p><\/p>\n<p><em>COMUNICATUR entervista al presidente del Grupo Hotusa, Amancio L&oacute;pez, coincidiendo con el 30 aniversario del Grupo. La compa&ntilde;&iacute;a cerr&oacute; 2007 con una facturaci&oacute;n de 714 millones de euros, con un crecimiento del 18% respecto al a&ntilde;o anterior; crece en n&uacute;mero de establecimientos asociados a sus cadenas de hoteles independientes (Hotusa Hotels y Keytel, entre otras); su divisi&oacute;n de explotaci&oacute;n hotelera, de la cual forma parte Eurostars Hotels, cuenta con un plan de expansi&oacute;n que contempla m&aacute;s de 20 aperturas durante los pr&oacute;ximos tres a&ntilde;os; y mantiene su apuesta firme por la diversificaci&oacute;n de sus l&iacute;neas de negocio y la internacionalizaci&oacute;n como fundamentos de su desarrollo. <br \/>\n<\/em><br \/>\n<em>Todo ello ha hecho que el Ministerio de Industria, Comercio y Turismo le haya concedido uno de los premios Pr&iacute;ncipe Felipe a la Excelencia Empresarial, galard&oacute;n que su presidente, Amancio L&oacute;pez Seijas, recoger&aacute; el pr&oacute;ximo 19 de junio en Madrid.<\/em> <\/p>\n<p><strong>&bull; Despu&eacute;s de facturar m&aacute;s de 700 millones de euros en 2007, &iquest;cu&aacute;l es la previsi&oacute;n para 2008? <br \/>\n<\/strong><br \/>\nLas cifras del pasado ejercicio son buenos sin ser excepcionales como las de 2006, en que la compa&ntilde;&iacute;a creci&oacute; un 32%. De cara al pr&oacute;ximo ejercicio, nuestra previsi&oacute;n es la de continuar creciendo a un ritmo superior al 15%. <\/p>\n<p><strong>&bull; Alguna vez ha se&ntilde;alado que estos porcentajes de crecimiento son una estrategia m&aacute;s que un objetivo&#8230;<\/strong> <\/p>\n<p>Efectivamente, nuestro objetivo final no es crecer por crecer sino ser una compa&ntilde;&iacute;a s&oacute;lida, sostenible en el tiempo. Basamos nuestra estrategia de expansi&oacute;n en dos pilares claros: la diversificaci&oacute;n en nuevas l&iacute;neas de negocio y la internacionalizaci&oacute;n. Los crecimientos experimentados en los &uacute;ltimos a&ntilde;os son el resultado de esta estrategia. <\/p>\n<p><strong>&bull; Tras abrir un hotel en el Caribe, &iquest;potenciar&aacute;n los resorts de lujo en zonas como esta o Brasil por encima de establecimientos urbanos en Europa?<\/strong> <\/p>\n<p>Entrar en destinos como el Caribe con una propuesta como la que ya existe no tiene sentido. Ya hay cadenas, en gran parte espa&ntilde;olas, que trabajan muy bien en este segmento. <\/p>\n<p>En cambio, en el &aacute;mbito de los resorts boutique, m&aacute;s selectos y exclusivos, dirigidos a un p&uacute;blico de alto poder adquisitivo, queda a&uacute;n camino por recorrer. Por esta raz&oacute;n adquirimos el Eurostars Blue Tulum 5*, en la Riviera Maya, y lo que queremos continuar haciendo, no s&oacute;lo en M&eacute;xico, sino en otros destinos de Am&eacute;rica como Brasil. <\/p>\n<p><strong>&bull; &iquest;En su estrategia priorizan la propiedad por encima de la gesti&oacute;n y el alquiler?<\/strong> <\/p>\n<p>En este sentido, y hasta ahora, tenemos un portafolio muy equilibrado. De los m&aacute;s de 85 hoteles que integran nuestra divisi&oacute;n de explotaci&oacute;n hotelera, cerca del 40% son de propiedad y en dos a&ntilde;os tendremos en marcha m&aacute;s de 25 proyectos de los cuales m&aacute;s de 15 son tambi&eacute;n en propiedad. De todas maneras, tambi&eacute;n tenemos previsto algunas nuevas incorporaciones en r&eacute;gimen de alquiler, aunque todo depende del an&aacute;lisis de cada proyecto. <\/p>\n<p><strong>&bull; &iquest;Cu&aacute;l ser&aacute; el siguiente hotel Eurostars?<\/strong> <\/p>\n<p>El Eurostars Madrid Tower 5*, que se inaugurar&aacute; el &uacute;ltimo trimestre de 2008. Por su ubicaci&oacute;n y caracter&iacute;sticas ser&aacute; un hotel emblem&aacute;tico, tanto para nuestra cadena Eurostars Hotels como para la ciudad de Madrid. <\/p>\n<p>Durante este 2008 tenemos otras aperturas previstas: un peque&ntilde;o hotel en el centro de Par&iacute;s (Eurostars Panorama), un cinco estrellas en Lisboa (Eurostars Das Letras) y un hotel boutique en pleno paseo de Gr&agrave;cia de Barcelona (Eurostars BCN Design). <\/p>\n<p>Eurostars Hotels se ha posicionado muy bien en el segmento de turismo de negocios. <\/p>\n<p><strong>&bull; &iquest;Considera que existe un exceso de oferta en las grandes capitales, como Barcelona?<\/strong> <\/p>\n<p>La saturaci&oacute;n de la oferta es un concepto que llevamos escuchando de manera recurrente en los &uacute;ltimos a&ntilde;os, no s&oacute;lo en Barcelona, sino en los principales destinos espa&ntilde;oles y europeos. Los buenos resultados del sector a finales de la d&eacute;cada de los 90 atrajeron a la hoteler&iacute;a a inversores que hasta aquel momento no se hab&iacute;an interesado. <\/p>\n<p>Pero estamos en un libre mercado y no creo que sea positivo pedir restricciones o moratorias; que sea el propio mercado el que marque si son o no necesarios tantos hoteles. <\/p>\n<p>Creo que la clave se basa en la concepci&oacute;n de establecimientos que apuesten por la especializaci&oacute;n y por una clara diferenciaci&oacute;n de la competencia. <\/p>\n<p><strong>&bull; &iquest;El turismo de reuniones, congresos y convenciones seguir&aacute; siendo un segmento clave en Barcelona?<\/strong> <\/p>\n<p>La buena evoluci&oacute;n de Barcelona en su posicionamiento como destino de primer orden a nivel internacional en este segmento es ejemplar. Los hoteleros somos los primeros beneficiados, no s&oacute;lo por las pernoctaciones que generan este tipo de eventos, sino por su efecto &ldquo;llamada&rdquo; y porque son una excelente carta de presentaci&oacute;n de la ciudad. <\/p>\n<p><strong>&bull; &iquest;C&oacute;mo afecta la actual crisis inmobiliaria al sector hotelero?<\/strong> <\/p>\n<p>Se est&aacute;n produciendo algunas operaciones de desinversi&oacute;n y probablemente ser&aacute; m&aacute;s dif&iacute;cil obtener financiaci&oacute;n para seg&uacute;n qu&eacute; proyectos. De momento, a nuestro grupo, no le ha afectado, pero somos conscientes que puede pasar dependiendo de c&oacute;mo evolucione la situaci&oacute;n econ&oacute;mica. <\/p>\n<p>El objetivo de ser una empresa sostenible radica precisamente en tener una estructura que evite que, en momentos de retroceso econ&oacute;mico, se resienta. <\/p>\n<p><strong>&bull; &iquest;La crisis hipotecaria de los EUA y la ca&iacute;da del d&oacute;lar tienen un reflejo en un descenso de la clientela norteamericana en los establecimientos Hotusa? <br \/>\n<\/strong><br \/>\nSiempre que se dan situaciones puntuales de este tipo, como la crisis del 11-S o recesiones econ&oacute;micas, los mercados emisores afectados se resienten. <\/p>\n<p>La clave radica, por un lado, en no tener una excesiva dependencia de un mercado concreto, y por otro, en prever estos hechos coyunturales y suavizar sus efectos captando nuevos clientes de otros mercados. <\/p>\n<p><strong>&bull; Los planes de expansi&oacute;n de Hotusa en China, &iquest;pueden verse frenados por los problemas pol&iacute;ticos que vive el pa&iacute;s? <\/p>\n<p><\/strong>China, y Asia en su extensi&oacute;n, es un destino interesante por su potencial de crecimiento, pero debido a sus particularidades requiere de un an&aacute;lisis m&aacute;s detallado. Forma parte de nuestra agenda, pero no a corto plazo. <\/p>\n<p>Por otro lado, la situaci&oacute;n pol&iacute;tica y jur&iacute;dica de un pa&iacute;s es uno de los aspectos que m&aacute;s valoramos a la hora de decidir nuestras inversiones. <\/p>\n<p><strong>&bull; &iquest;Contemplan la posibilidad de entrar en el mercado burs&aacute;til?<\/strong> <\/p>\n<p>No. La f&oacute;rmula que hemos mantenido en estos 30 a&ntilde;os de historia ha demostrado que es exitosa y creo que a&uacute;n tiene recorrido. <\/p>\n<p><strong>&bull; &iquest;Cu&aacute;l ser&iacute;a el valor intangible, el elemento diferenciador, de Hotusa? <br \/>\n<\/strong><br \/>\nEstoy convencido que el &eacute;xito se basa en las personas que forman parte de este proyecto. Creo que nuestro m&eacute;rito ha sido atraer gente con mucho talento, ilusi&oacute;n, dedicaci&oacute;n y profesionalidad. Algunas de estas personas trabajan aqu&iacute; desde la creaci&oacute;n del grupo en 1977. Adem&aacute;s hemos hecho una apuesta firme por la promoci&oacute;n interna y para establecer una escuela permanente en la que, adem&aacute;s del conocimiento del oficio, se transmiten los valores de la compa&ntilde;&iacute;a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&quot;Estamos en el libre mercado y no creo que sea bueno pedir restricciones o moratorias de ning&uacute;n tipo; que sea el propio mercado quien diga si son necesarios tantos hoteles&quot;<\/p>\n<p><em><img class=\"\" height=\"179\" alt=\"\" width=\"153\" src=\"https:\/\/www.comunicatur.info\/cms\/images\/stories\/fotos\/AmancioLopez.jpg\" \/><\/em><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"close","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[151],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/320"}],"collection":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/comments?post=320"}],"version-history":[{"count":0,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/320\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/media?parent=320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/categories?post=320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/tags?post=320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}