{"id":1040,"date":"2009-01-29T00:00:00","date_gmt":"2009-01-29T00:00:00","guid":{"rendered":"https:\/\/comunicatur.info\/la-spanair-catalana-haura-desperar-2\/"},"modified":"2009-01-29T00:00:00","modified_gmt":"2009-01-29T00:00:00","slug":"la-spanair-catalana-haura-desperar-2","status":"publish","type":"post","link":"https:\/\/www.comunicatur.info\/es\/la-spanair-catalana-haura-desperar-2\/","title":{"rendered":"La Spanair catalana tendr\u00e1 que esperar"},"content":{"rendered":"<p>Tras la publicaci&oacute;n de algunas informaciones que daban pr&aacute;cticamente como un hecho la compra de Spanair por inversores catalanes, han aparecido las primeras voces que matizan la operaci&oacute;n.<\/p>\n<p><\/p>\n<p>El conseller de Innovaci&oacute;n, Universidades y Empresa, Josep Huguet, no se ha querido desentender de la operaci&oacute;n pero s&iacute; que ha dejado claro que se trata de una decisi&oacute;n empresarial y que en todo caso la Administraci&oacute;n facilitar&iacute;a capital p&uacute;blico de forma indirecta.<\/p>\n<p>Parece que la operaci&oacute;n est&aacute; avanzada pero necesita m&aacute;s inversores. &ldquo;Habr&aacute; que buscar aliados si no hay capital catal&aacute;n suficiente&rdquo;, ha declarado Huguet. Algunos califican de globos sonda la informaci&oacute;n que da&nbsp;por&nbsp;hecha la venta. La intencionalidad de esta noticia ser&iacute;a la de animar a algunos empresarios a aportar parte del dinero que&nbsp;falta para completar la operaci&oacute;n.<\/p>\n<p>El conseller Huguet ha abierto la puerta a la entrada de capital de pa&iacute;ses del Oriente Medio. &ldquo;Haremos contactos internacionales para encontrar capital adicional&rdquo; ha comentado Huguet, quien ha confirmado que los pa&iacute;ses &aacute;rabes pueden ser una alternativa inversora que permita ayudar a crear un hub&nbsp;en El&nbsp;Prat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la publicaci&oacute;n de algunas informaciones que daban pr&aacute;cticamente como un hecho la compra de Spanair por inversores catalanes, han aparecido las primeras voces que matizan la operaci&oacute;n.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"close","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/1040"}],"collection":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/comments?post=1040"}],"version-history":[{"count":0,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/posts\/1040\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/media?parent=1040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/categories?post=1040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicatur.info\/es\/wp-json\/wp\/v2\/tags?post=1040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}